{"id":145353,"date":"2023-01-27T11:44:05","date_gmt":"2023-01-27T03:44:05","guid":{"rendered":"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/?p=145353"},"modified":"2023-01-27T11:47:37","modified_gmt":"2023-01-27T03:47:37","slug":"princess-connect-imas-collab-feb-1","status":"publish","type":"post","link":"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/post\/145353\/princess-connect-imas-collab-feb-1","title":{"rendered":"Princess Connect! Re: Dive x The Idolm@ster Cinderella Girls Collab Begins on February 1"},"content":{"rendered":"\n<p>That&#8217;s right, <a href=\"https:\/\/apps.qoo-app.com\/en\/app\/16051\"><strong>Princess Connect! Re: Dive <\/strong><\/a>is collaborating with The Idolm@ster Cinderella Girls, bringing some of your favorite idols to the world of Princess Connect!<\/p>\n\n\n\n<p>When the event starts you can pick up characters like Uzuki, Rin, and Mio from IM@S CG, and also enjoy the brand new event story featuring the girls as they bedazzle the new world they find themselves in, and enjoy loads of bonuses like increased player EXP, more master coins, sanctum survey and temple trek tickets and more!<\/p>\n\n\n\n<p>The Princess Connect x Idolm@ster Cinderella Girls event begins on February 1<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color: #33cccc\"><strong>\u258d<\/strong><\/span> Princess Connect x Idolm@ster Cinderella Girls Collab Gacha<\/h2>\n\n\n\n<p>The Idolm@ster girls are showing up in two separate focus gachas! You can pick up Uzuki and Rin in their focus gachas, both running for 13 days separately from February 1 to February 14, and February 14 to February 27.<\/p>\n\n\n\n<p>Like with other limited characters, the pair won&#8217;t be appearing in the game&#8217;s regular gacha when they leave, so make sure you pick them up while they&#8217;re still around!<\/p>\n\n\n\n<p><strong>\u25a0 Uzuki (IM@S CG)<\/strong><\/p>\n\n\n\n<p>Uzuki is armed with a big sword and even bigger smile, as her toolkit revolves around dealing damage while also buffing her allies through the power of song and cheers. Even in a foreign world, Uzuki is ready to do her best! <\/p>\n\n\n\n<figure class=\"wp-block-image alignwide size-large\"><img data-attachment-id=\"145356\" data-permalink=\"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/post\/145353\/princess-connect-imas-collab-feb-1\/princess_connect_idolmaster_collab_0-1#main\" data-orig-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-1.jpg?fit=900%2C506&amp;ssl=1\" data-orig-size=\"900,506\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Princess_connect_Idolmaster_collab_0 (1)\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-1.jpg?fit=460%2C259&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-1.jpg?fit=900%2C506&amp;ssl=1\" fetchpriority=\"high\" decoding=\"async\" width=\"900\" height=\"506\" src=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-1.jpg?resize=900%2C506&#038;ssl=1\" alt=\"\" class=\"wp-image-145356\" srcset=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-1.jpg?w=900&amp;ssl=1 900w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-1.jpg?resize=460%2C259&amp;ssl=1 460w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-1.jpg?resize=768%2C432&amp;ssl=1 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" title=\"\" data-recalc-dims=\"1\"><\/figure>\n\n\n\n<p><strong>\u25a0 Rin (IM@S CG)<\/strong><\/p>\n\n\n\n<p>This cool calm and collected friend of Uzuki also finds herself in Landosol, but it&#8217;s going to take a lot more than a change of scenery to shake her. She specializes as a physical damage dealer that can bind enemies and reduce their defenses, while also putting up her own shield to keep her healthy in combat. She can do anything she puts her mind to when she&#8217;s serious, which sure is bad for the enemy!<\/p>\n\n\n\n<figure class=\"wp-block-image alignwide size-large\"><img data-attachment-id=\"145357\" data-permalink=\"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/post\/145353\/princess-connect-imas-collab-feb-1\/princess_connect_idolmaster_collab_0-2#main\" data-orig-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-2.jpg?fit=900%2C506&amp;ssl=1\" data-orig-size=\"900,506\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Princess_connect_Idolmaster_collab_0 (2)\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-2.jpg?fit=460%2C259&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-2.jpg?fit=900%2C506&amp;ssl=1\" decoding=\"async\" width=\"900\" height=\"506\" src=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-2.jpg?resize=900%2C506&#038;ssl=1\" alt=\"\" class=\"wp-image-145357\" srcset=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-2.jpg?w=900&amp;ssl=1 900w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-2.jpg?resize=460%2C259&amp;ssl=1 460w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-2.jpg?resize=768%2C432&amp;ssl=1 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" title=\"\" data-recalc-dims=\"1\"><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color: #33cccc\"><strong>\u258d<\/strong><\/span> Princess Connect x Idolm@ster Cinderella Girls Story Event<\/h2>\n\n\n\n<p>The original Cinderella Girls trio will be debuting in the game&#8217;s new story event. Ploay through this event and special missions to unlock Mio (IM@S CG) for free!<\/p>\n\n\n\n<p>In addition, the experience gain rates will also be increased to 1.5x its normal value during this event, making it easier for new players to catch up to levels, and veterans to level up more quickly!<\/p>\n\n\n\n<figure class=\"wp-block-image alignwide size-large\"><img data-attachment-id=\"145360\" data-permalink=\"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/post\/145353\/princess-connect-imas-collab-feb-1\/princess_connect_idolmaster_collab_0-5#main\" data-orig-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-5.jpg?fit=900%2C506&amp;ssl=1\" data-orig-size=\"900,506\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Princess_connect_Idolmaster_collab_0 (5)\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-5.jpg?fit=460%2C259&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-5.jpg?fit=900%2C506&amp;ssl=1\" decoding=\"async\" width=\"900\" height=\"506\" src=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-5.jpg?resize=900%2C506&#038;ssl=1\" alt=\"\" class=\"wp-image-145360\" srcset=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-5.jpg?w=900&amp;ssl=1 900w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-5.jpg?resize=460%2C259&amp;ssl=1 460w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-5.jpg?resize=768%2C432&amp;ssl=1 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" title=\"\" data-recalc-dims=\"1\"><\/figure>\n\n\n\n<figure class=\"wp-block-image alignwide size-large\"><img data-attachment-id=\"145362\" data-permalink=\"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/post\/145353\/princess-connect-imas-collab-feb-1\/princess_connect_idolmaster_collab_0-7#main\" data-orig-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-7.jpg?fit=640%2C350&amp;ssl=1\" data-orig-size=\"640,350\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Princess_connect_Idolmaster_collab_0 (7)\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-7.jpg?fit=460%2C252&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-7.jpg?fit=640%2C350&amp;ssl=1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"350\" src=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-7.jpg?resize=640%2C350&#038;ssl=1\" alt=\"\" class=\"wp-image-145362\" srcset=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-7.jpg?w=640&amp;ssl=1 640w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-7.jpg?resize=460%2C252&amp;ssl=1 460w\" sizes=\"(max-width: 640px) 100vw, 640px\" title=\"\" data-recalc-dims=\"1\"><\/figure>\n\n\n\n<figure class=\"wp-block-image alignwide size-large\"><img data-attachment-id=\"145361\" data-permalink=\"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/post\/145353\/princess-connect-imas-collab-feb-1\/princess_connect_idolmaster_collab_0-6#main\" data-orig-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-6.jpg?fit=1200%2C630&amp;ssl=1\" data-orig-size=\"1200,630\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Princess_connect_Idolmaster_collab_0 (6)\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-6.jpg?fit=460%2C242&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-6.jpg?fit=1200%2C630&amp;ssl=1\" loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"630\" src=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-6.jpg?resize=1200%2C630&#038;ssl=1\" alt=\"\" class=\"wp-image-145361\" srcset=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-6.jpg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-6.jpg?resize=460%2C242&amp;ssl=1 460w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-6.jpg?resize=768%2C403&amp;ssl=1 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" title=\"\" data-recalc-dims=\"1\"><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color: #33cccc\"><strong>\u258d<\/strong><\/span> New Gachas<\/h2>\n\n\n\n<p>After the IM@S CG gachas, Princess Connect will still be adding much more new content with the Prize Gacha and premium gacha.<\/p>\n\n\n\n<p>The prize gacha looks to add a bit of summer warmth back to the cold winter, with Catch Makoto (Summer) and Maho (Summer) being up for grabs with this five-day prize gacha centered around the pair. when performing draws on the Prize Gacha, you\u2019ll first choose one of the two characters to receive extra bonus rewards for. These bonuses range in anything from Divine Amulets to extra Memory Shards of your chosen character!<\/p>\n\n\n\n<figure class=\"wp-block-image alignwide size-large\"><img data-attachment-id=\"145358\" data-permalink=\"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/post\/145353\/princess-connect-imas-collab-feb-1\/princess_connect_idolmaster_collab_0-3#main\" data-orig-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-3.jpg?fit=900%2C506&amp;ssl=1\" data-orig-size=\"900,506\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Princess_connect_Idolmaster_collab_0 (3)\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-3.jpg?fit=460%2C259&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-3.jpg?fit=900%2C506&amp;ssl=1\" loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"506\" src=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-3.jpg?resize=900%2C506&#038;ssl=1\" alt=\"\" class=\"wp-image-145358\" srcset=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-3.jpg?w=900&amp;ssl=1 900w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-3.jpg?resize=460%2C259&amp;ssl=1 460w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-3.jpg?resize=768%2C432&amp;ssl=1 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" title=\"\" data-recalc-dims=\"1\"><\/figure>\n\n\n\n<p>A 3\u2605 Guaranteed Premium Gacha is also back, letting you do 10-pull on the current Premium Gacha rotation with premium jewels, to give you at least one 3\u2605! This gacha begins on February 14, and if you&#8217;re lucky, it&#8217;s also one way to pick up Rin (IM@S CG)!<\/p>\n\n\n\n<figure class=\"wp-block-image alignwide size-large\"><img data-attachment-id=\"145359\" data-permalink=\"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/post\/145353\/princess-connect-imas-collab-feb-1\/princess_connect_idolmaster_collab_0-4#main\" data-orig-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-4.jpg?fit=1200%2C630&amp;ssl=1\" data-orig-size=\"1200,630\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Princess_connect_Idolmaster_collab_0 (4)\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-4.jpg?fit=460%2C242&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-4.jpg?fit=1200%2C630&amp;ssl=1\" loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"630\" src=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-4.jpg?resize=1200%2C630&#038;ssl=1\" alt=\"\" class=\"wp-image-145359\" srcset=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-4.jpg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-4.jpg?resize=460%2C242&amp;ssl=1 460w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-4.jpg?resize=768%2C403&amp;ssl=1 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" title=\"\" data-recalc-dims=\"1\"><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color: #33cccc\"><strong>\u258d<\/strong><\/span> The Case of the Woeful Stalker Revival<\/h2>\n\n\n\n<p>The Case of the Woeful Stalker story event is also getting a revival, letting you enjoy a classic mystery with Makoto, Kasumi, and Ayumi on the streets of Landosol! Like with the IM@S story event you&#8217;ll also get a bonus 1.5 player EXP when playing event quests.<\/p>\n\n\n\n<figure class=\"wp-block-image alignwide size-large\"><img data-attachment-id=\"145363\" data-permalink=\"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/post\/145353\/princess-connect-imas-collab-feb-1\/princess_connect_idolmaster_collab_0-8#main\" data-orig-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-8.jpg?fit=900%2C506&amp;ssl=1\" data-orig-size=\"900,506\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Princess_connect_Idolmaster_collab_0 (8)\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-8.jpg?fit=460%2C259&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-8.jpg?fit=900%2C506&amp;ssl=1\" loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"506\" src=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-8.jpg?resize=900%2C506&#038;ssl=1\" alt=\"\" class=\"wp-image-145363\" srcset=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-8.jpg?w=900&amp;ssl=1 900w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-8.jpg?resize=460%2C259&amp;ssl=1 460w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-8.jpg?resize=768%2C432&amp;ssl=1 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" title=\"\" data-recalc-dims=\"1\"><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color: #33cccc\"><strong>\u258d<\/strong><\/span> February New Dungeons and Bosses<\/h2>\n\n\n\n<p>February also comes with a whole bunch of new features, including that month&#8217;s Tower of Luna, and it&#8217;ll be updated with the new Floor Skip Feature!<\/p>\n\n\n\n<figure class=\"wp-block-image alignwide size-large\"><img data-attachment-id=\"145364\" data-permalink=\"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/post\/145353\/princess-connect-imas-collab-feb-1\/princess_connect_idolmaster_collab_0-9#main\" data-orig-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-9.jpg?fit=900%2C506&amp;ssl=1\" data-orig-size=\"900,506\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Princess_connect_Idolmaster_collab_0 (9)\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-9.jpg?fit=460%2C259&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-9.jpg?fit=900%2C506&amp;ssl=1\" loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"506\" src=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-9.jpg?resize=900%2C506&#038;ssl=1\" alt=\"\" class=\"wp-image-145364\" srcset=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-9.jpg?w=900&amp;ssl=1 900w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-9.jpg?resize=460%2C259&amp;ssl=1 460w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-9.jpg?resize=768%2C432&amp;ssl=1 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" title=\"\" data-recalc-dims=\"1\"><\/figure>\n\n\n\n<p>Clan battles are also coming, with Mesarthim making an appearance this time around, and Jadewyrm&#8217;s Roost is here with a brand new Extreme III Dungeon difficulty! Take on these challenges alone or with your friends and reap tons of rewards!<\/p>\n\n\n\n<figure class=\"wp-block-image alignwide size-large\"><img data-attachment-id=\"145365\" data-permalink=\"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/post\/145353\/princess-connect-imas-collab-feb-1\/princess_connect_idolmaster_collab_0-10#main\" data-orig-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-10.jpg?fit=900%2C506&amp;ssl=1\" data-orig-size=\"900,506\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Princess_connect_Idolmaster_collab_0 (10)\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-10.jpg?fit=460%2C259&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-10.jpg?fit=900%2C506&amp;ssl=1\" loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"506\" src=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-10.jpg?resize=900%2C506&#038;ssl=1\" alt=\"\" class=\"wp-image-145365\" srcset=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-10.jpg?w=900&amp;ssl=1 900w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-10.jpg?resize=460%2C259&amp;ssl=1 460w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-10.jpg?resize=768%2C432&amp;ssl=1 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" title=\"\" data-recalc-dims=\"1\"><\/figure>\n\n\n\n<figure class=\"wp-block-image alignwide size-large\"><img data-attachment-id=\"145367\" data-permalink=\"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/post\/145353\/princess-connect-imas-collab-feb-1\/princess_connect_idolmaster_collab_0-12#main\" data-orig-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-12.jpg?fit=900%2C506&amp;ssl=1\" data-orig-size=\"900,506\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Princess_connect_Idolmaster_collab_0 (12)\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-12.jpg?fit=460%2C259&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-12.jpg?fit=900%2C506&amp;ssl=1\" loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"506\" src=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-12.jpg?resize=900%2C506&#038;ssl=1\" alt=\"\" class=\"wp-image-145367\" srcset=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-12.jpg?w=900&amp;ssl=1 900w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-12.jpg?resize=460%2C259&amp;ssl=1 460w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-12.jpg?resize=768%2C432&amp;ssl=1 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" title=\"\" data-recalc-dims=\"1\"><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color: #33cccc\"><strong>\u258d<\/strong><\/span> New Ascensions<\/h2>\n\n\n\n<p>The Twinkle Wish Trio is finally also getting an update with new 6\u2605 variants, coming on February 1! These variants come with enhanced skills and are even stronger, sporting a brand-new look on top of that.<\/p>\n\n\n\n<p>You can unlock these variants by playing Very Hard main quest stages, and you can challenge the new stages at 20-3, 21-1. and 21-2 for the Twinkle Wish Trio.<\/p>\n\n\n\n<figure class=\"wp-block-image alignwide size-large\"><img data-attachment-id=\"145366\" data-permalink=\"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/post\/145353\/princess-connect-imas-collab-feb-1\/princess_connect_idolmaster_collab_0-11#main\" data-orig-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-11.jpg?fit=900%2C506&amp;ssl=1\" data-orig-size=\"900,506\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Princess_connect_Idolmaster_collab_0 (11)\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-11.jpg?fit=460%2C259&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-11.jpg?fit=900%2C506&amp;ssl=1\" loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"506\" src=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-11.jpg?resize=900%2C506&#038;ssl=1\" alt=\"\" class=\"wp-image-145366\" srcset=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-11.jpg?w=900&amp;ssl=1 900w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-11.jpg?resize=460%2C259&amp;ssl=1 460w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-11.jpg?resize=768%2C432&amp;ssl=1 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" title=\"\" data-recalc-dims=\"1\"><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color: #33cccc\"><strong>\u258d<\/strong><\/span> Increased Drop Campaign<\/h2>\n\n\n\n<p>And of course to celebrate, the game&#8217;s running a campaign for 1.5x Master Coins and triple drops for Sanctum Survey and Temple Treks, making it far easier for you to refine your character&#8217;s max potential equipment. The master coins event begins from February 1 to February 13, while the Sanctum Survey and Temple Trek event only lasts for a few days from February 23, to February 27. so make sure you don&#8217;t miss out!<\/p>\n\n\n\n<figure class=\"wp-block-image alignwide size-large\"><img data-attachment-id=\"145368\" data-permalink=\"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/post\/145353\/princess-connect-imas-collab-feb-1\/princess_connect_idolmaster_collab_0-13#main\" data-orig-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-13.jpg?fit=900%2C506&amp;ssl=1\" data-orig-size=\"900,506\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Princess_connect_Idolmaster_collab_0 (13)\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-13.jpg?fit=460%2C259&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-13.jpg?fit=900%2C506&amp;ssl=1\" loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"506\" src=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-13.jpg?resize=900%2C506&#038;ssl=1\" alt=\"\" class=\"wp-image-145368\" srcset=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-13.jpg?w=900&amp;ssl=1 900w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-13.jpg?resize=460%2C259&amp;ssl=1 460w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-13.jpg?resize=768%2C432&amp;ssl=1 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" title=\"\" data-recalc-dims=\"1\"><\/figure>\n\n\n\n<figure class=\"wp-block-image alignwide size-large\"><img data-attachment-id=\"145369\" data-permalink=\"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/post\/145353\/princess-connect-imas-collab-feb-1\/princess_connect_idolmaster_collab_0-14#main\" data-orig-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-14.jpg?fit=900%2C506&amp;ssl=1\" data-orig-size=\"900,506\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Princess_connect_Idolmaster_collab_0 (14)\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-14.jpg?fit=460%2C259&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-14.jpg?fit=900%2C506&amp;ssl=1\" loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"506\" src=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-14.jpg?resize=900%2C506&#038;ssl=1\" alt=\"\" class=\"wp-image-145369\" srcset=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-14.jpg?w=900&amp;ssl=1 900w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-14.jpg?resize=460%2C259&amp;ssl=1 460w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/Princess_connect_Idolmaster_collab_0-14.jpg?resize=768%2C432&amp;ssl=1 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" title=\"\" data-recalc-dims=\"1\"><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><span style=\"color: #000000\"><span style=\"color: #000000\"><span style=\"color: #000000\">Follow QooApp&#8217;s official\u00a0<a href=\"https:\/\/www.facebook.com\/QooAppGlobal\" target=\"_blank\" rel=\"noopener\">Facebook<\/a>\u00a0\/\u00a0<a href=\"https:\/\/twitter.com\/QooApp_EN\" target=\"_blank\" rel=\"noopener\">Twitter<\/a>\u00a0\/\u00a0<a href=\"https:\/\/news.google.com\/s\/CBIwlaatzoIB?sceid=US:en&amp;sceid=US:en\" target=\"_blank\" rel=\"noopener\">Google News<\/a> \/ <strong><a href=\"https:\/\/www.reddit.com\/r\/qooapp\/\" target=\"_blank\" rel=\"noopener\">Reddit<\/a><\/strong>\/ <strong><a href=\"https:\/\/r.qoo-app.com\/subyt\">Youtube<\/a><\/strong>\u00a0to get the latest ACG information!<\/span><\/span><\/span><\/h3>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-embed-handler wp-block-embed-embed-handler\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"fb-post\" data-href=\"https:\/\/www.facebook.com\/QooAppGlobal\/posts\/904099287519394\" data-width=\"552\"><\/div>\n<\/div><\/figure>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex\">\n<div class=\"wp-block-button is-style-fill\"><a class=\"wp-block-button__link has-text-color has-background\" href=\"https:\/\/www.crunchyroll.com\/games\/index.html\" style=\"background-color:#75bfc6;color:#ffffff\" target=\"_blank\" rel=\"noreferrer noopener\">Official Site<\/a><\/div>\n\n\n\n<div class=\"wp-block-button is-style-fill\"><a class=\"wp-block-button__link has-text-color has-background\" href=\"https:\/\/twitter.com\/playCRgames\" style=\"background-color:#75bfc6;color:#ffffff\" target=\"_blank\" rel=\"noreferrer noopener\">Official Twitter<\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>The Princess Connect! Re: Dive x The Idolm@ster Cinderella Girls collab event begins on February 1! Pick up Uzuki, Rin, and Mio in the new gachas and story!<\/p>\n","protected":false},"author":27,"featured_media":145355,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[19,3],"tags":[10134,13,4219,1207,17,16210,6337,2300],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2023\/01\/princess_connect-idol_master_feature.jpg?fit=1200%2C678&ssl=1","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pe8G4K-BOp","_links":{"self":[{"href":"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-json\/wp\/v2\/posts\/145353"}],"collection":[{"href":"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-json\/wp\/v2\/comments?post=145353"}],"version-history":[{"count":0,"href":"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-json\/wp\/v2\/posts\/145353\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-json\/wp\/v2\/media\/145355"}],"wp:attachment":[{"href":"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-json\/wp\/v2\/media?parent=145353"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-json\/wp\/v2\/categories?post=145353"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-json\/wp\/v2\/tags?post=145353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}