{"id":30340,"date":"2018-06-20T14:54:28","date_gmt":"2018-06-20T06:54:28","guid":{"rendered":"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/?p=30340"},"modified":"2018-06-20T14:54:28","modified_gmt":"2018-06-20T06:54:28","slug":"qoo-news-nintendo-releases-overview-trailer-captain-toad-treasure-tracker","status":"publish","type":"post","link":"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/post\/30340\/qoo-news-nintendo-releases-overview-trailer-captain-toad-treasure-tracker","title":{"rendered":"[Qoo News] Nintendo Releases Overview Trailer for Captain Toad: Treasure Tracker"},"content":{"rendered":"<p>Nintendo has released a new Japanese overview trailer for their upcoming Switch and 3DS title featuring Toad, Captain Toad: Treasure Tracker.<\/p>\n<p><img data-attachment-id=\"30344\" data-permalink=\"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/post\/30340\/qoo-news-nintendo-releases-overview-trailer-captain-toad-treasure-tracker\/attachment\/18062006442534#main\" data-orig-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006442534.jpg?fit=1920%2C1080&amp;ssl=1\" data-orig-size=\"1920,1080\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"18062006442534\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006442534.jpg?fit=300%2C169&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006442534.jpg?fit=1024%2C576&amp;ssl=1\" fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-30344\" src=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006442534.jpg?resize=1200%2C675&#038;ssl=1\" alt=\"\" width=\"1200\" height=\"675\" srcset=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006442534.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006442534.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006442534.jpg?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006442534.jpg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006442534.jpg?resize=460%2C260&amp;ssl=1 460w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" title=\"\" data-recalc-dims=\"1\"><\/p>\n<p>The five-minute trailer sets the story for Captain Toad&#8217;s journey to retrieve the power star. The trailer features game footage on the different features of the game including different stages, in-game items and their effects, challenges, different game modes, as well as the co-op mode.<\/p>\n<p><img data-attachment-id=\"30346\" data-permalink=\"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/post\/30340\/qoo-news-nintendo-releases-overview-trailer-captain-toad-treasure-tracker\/attachment\/18062006484190#main\" data-orig-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006484190.jpg?fit=1920%2C1080&amp;ssl=1\" data-orig-size=\"1920,1080\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"18062006484190\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006484190.jpg?fit=300%2C169&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006484190.jpg?fit=1024%2C576&amp;ssl=1\" decoding=\"async\" class=\"aligncenter size-full wp-image-30346\" src=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006484190.jpg?resize=1200%2C675&#038;ssl=1\" alt=\"\" width=\"1200\" height=\"675\" srcset=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006484190.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006484190.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006484190.jpg?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006484190.jpg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006484190.jpg?resize=460%2C260&amp;ssl=1 460w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" title=\"\" data-recalc-dims=\"1\"><\/p>\n<p><img data-attachment-id=\"30347\" data-permalink=\"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/post\/30340\/qoo-news-nintendo-releases-overview-trailer-captain-toad-treasure-tracker\/attachment\/18062006485893#main\" data-orig-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006485893.jpg?fit=1920%2C1080&amp;ssl=1\" data-orig-size=\"1920,1080\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"18062006485893\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006485893.jpg?fit=300%2C169&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006485893.jpg?fit=1024%2C576&amp;ssl=1\" decoding=\"async\" class=\"aligncenter size-full wp-image-30347\" src=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006485893.jpg?resize=1200%2C675&#038;ssl=1\" alt=\"\" width=\"1200\" height=\"675\" srcset=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006485893.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006485893.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006485893.jpg?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006485893.jpg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006485893.jpg?resize=460%2C260&amp;ssl=1 460w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" title=\"\" data-recalc-dims=\"1\"><\/p>\n<p><img data-attachment-id=\"30348\" data-permalink=\"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/post\/30340\/qoo-news-nintendo-releases-overview-trailer-captain-toad-treasure-tracker\/attachment\/1806200649194#main\" data-orig-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/1806200649194.jpg?fit=1920%2C1080&amp;ssl=1\" data-orig-size=\"1920,1080\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"1806200649194\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/1806200649194.jpg?fit=300%2C169&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/1806200649194.jpg?fit=1024%2C576&amp;ssl=1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-30348\" src=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/1806200649194.jpg?resize=1200%2C675&#038;ssl=1\" alt=\"\" width=\"1200\" height=\"675\" srcset=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/1806200649194.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/1806200649194.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/1806200649194.jpg?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/1806200649194.jpg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/1806200649194.jpg?resize=460%2C260&amp;ssl=1 460w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" title=\"\" data-recalc-dims=\"1\"><\/p>\n<p><img data-attachment-id=\"30342\" data-permalink=\"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/post\/30340\/qoo-news-nintendo-releases-overview-trailer-captain-toad-treasure-tracker\/attachment\/18062006441154#main\" data-orig-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006441154.jpg?fit=1920%2C1080&amp;ssl=1\" data-orig-size=\"1920,1080\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"18062006441154\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006441154.jpg?fit=300%2C169&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006441154.jpg?fit=1024%2C576&amp;ssl=1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-30342\" src=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006441154.jpg?resize=1200%2C675&#038;ssl=1\" alt=\"\" width=\"1200\" height=\"675\" srcset=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006441154.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006441154.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006441154.jpg?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006441154.jpg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006441154.jpg?resize=460%2C260&amp;ssl=1 460w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" title=\"\" data-recalc-dims=\"1\"><\/p>\n<p><img data-attachment-id=\"30349\" data-permalink=\"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/post\/30340\/qoo-news-nintendo-releases-overview-trailer-captain-toad-treasure-tracker\/attachment\/18062006500355#main\" data-orig-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006500355.jpg?fit=1920%2C1080&amp;ssl=1\" data-orig-size=\"1920,1080\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"18062006500355\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006500355.jpg?fit=300%2C169&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006500355.jpg?fit=1024%2C576&amp;ssl=1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-30349\" src=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006500355.jpg?resize=1200%2C675&#038;ssl=1\" alt=\"\" width=\"1200\" height=\"675\" srcset=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006500355.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006500355.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006500355.jpg?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006500355.jpg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006500355.jpg?resize=460%2C260&amp;ssl=1 460w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" title=\"\" data-recalc-dims=\"1\"><\/p>\n<p><img data-attachment-id=\"30343\" data-permalink=\"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/post\/30340\/qoo-news-nintendo-releases-overview-trailer-captain-toad-treasure-tracker\/attachment\/18062006441383#main\" data-orig-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006441383.jpg?fit=1920%2C1080&amp;ssl=1\" data-orig-size=\"1920,1080\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"18062006441383\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006441383.jpg?fit=300%2C169&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006441383.jpg?fit=1024%2C576&amp;ssl=1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-30343\" src=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006441383.jpg?resize=1200%2C675&#038;ssl=1\" alt=\"\" width=\"1200\" height=\"675\" srcset=\"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006441383.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006441383.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006441383.jpg?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006441383.jpg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006441383.jpg?resize=460%2C260&amp;ssl=1 460w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" title=\"\" data-recalc-dims=\"1\"><\/p>\n<p>Captain Toad Treasure Tracker is a Hakoniwa (Japanese Box Garden) style puzzle solver with maps from Mario Odessey. The Game will feature a co-op mode for players to pair up with a friend who will act as support.<\/p>\n<p>Captain Toad Treasure Tracker is due out 13th July in Japan for 3DS and Switch.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nintendo has released a new Japanese overview trailer for their upcoming Switch and 3DS title featuring Toad, Captain Toad: Treasure Tracker.<\/p>\n","protected":false},"author":1,"featured_media":30350,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[19,774],"tags":[912,4742,4219,295,976],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-content\/uploads\/sites\/3\/2018\/06\/18062006534928.jpg?fit=1920%2C1080&ssl=1","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pe8G4K-7Tm","_links":{"self":[{"href":"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-json\/wp\/v2\/posts\/30340"}],"collection":[{"href":"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-json\/wp\/v2\/comments?post=30340"}],"version-history":[{"count":0,"href":"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-json\/wp\/v2\/posts\/30340\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-json\/wp\/v2\/media\/30350"}],"wp:attachment":[{"href":"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-json\/wp\/v2\/media?parent=30340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-json\/wp\/v2\/categories?post=30340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-json\/wp\/v2\/tags?post=30340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}