{"id":14783,"count":1,"description":"","link":"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/tag\/tristia-of-the-deep-blue-sea-legacy","name":"Tristia of the Deep-Blue Sea: Legacy","slug":"tristia-of-the-deep-blue-sea-legacy","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-json\/wp\/v2\/tags\/14783"}],"collection":[{"href":"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-json\/wp\/v2\/posts?tags=14783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}