{"id":17150,"count":1,"description":"","link":"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/tag\/the-portopia-serial-murder-case","name":"The Portopia Serial Murder Case","slug":"the-portopia-serial-murder-case","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-json\/wp\/v2\/tags\/17150"}],"collection":[{"href":"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-json\/wp\/v2\/posts?tags=17150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}