{"id":17576,"count":1,"description":"","link":"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/tag\/netflix-games","name":"Netflix Games","slug":"netflix-games","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-json\/wp\/v2\/tags\/17576"}],"collection":[{"href":"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-json\/wp\/v2\/posts?tags=17576"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}