{"id":2578,"count":1,"description":"","link":"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/tag\/chain-blood%e2%80%95%e3%81%8b%e3%81%9e%e3%81%8f%e5%a9%9a%e2%80%95","name":"Chain Blood\u2015\u304b\u305e\u304f\u5a5a\u2015","slug":"chain-blood%e2%80%95%e3%81%8b%e3%81%9e%e3%81%8f%e5%a9%9a%e2%80%95","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-json\/wp\/v2\/tags\/2578"}],"collection":[{"href":"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/d27fq2mgp64qlg.cloudfront.net\/en\/wp-json\/wp\/v2\/posts?tags=2578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}